{"id":20591,"date":"2015-05-22T09:21:49","date_gmt":"2015-05-22T08:21:49","guid":{"rendered":"http:\/\/www.jeanpierrevangorp.info\/site\/?p=20591"},"modified":"2015-05-22T09:21:49","modified_gmt":"2015-05-22T08:21:49","slug":"un-parc-de-8-hectares-a-reyers","status":"publish","type":"post","link":"https:\/\/www.jeanpierrevangorp.info\/site\/un-parc-de-8-hectares-a-reyers\/","title":{"rendered":"Un parc de 8 hectares \u00e0 Reyers"},"content":{"rendered":"<p style=\"text-align: center;\"><a href=\"https:\/\/www.jeanpierrevangorp.info\/site\/wp-content\/uploads\/2015\/05\/Schema-Directeur-Reyers-728x542.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-20592\" alt=\"Schema-Directeur-Reyers-728x542\" src=\"https:\/\/www.jeanpierrevangorp.info\/site\/wp-content\/uploads\/2015\/05\/Schema-Directeur-Reyers-728x542-464x345.jpg\" width=\"464\" height=\"345\" srcset=\"https:\/\/www.jeanpierrevangorp.info\/site\/wp-content\/uploads\/2015\/05\/Schema-Directeur-Reyers-728x542-464x345.jpg 464w, https:\/\/www.jeanpierrevangorp.info\/site\/wp-content\/uploads\/2015\/05\/Schema-Directeur-Reyers-728x542.jpg 728w\" sizes=\"(max-width: 464px) 100vw, 464px\" \/><\/a><\/p>\n<p>L&rsquo;un des grands projets de la<strong> R\u00e9gion de Bruxelles-Capitale<\/strong> est la<strong> Cit\u00e9 des M\u00e9dias \u00e0 Reyers<\/strong>. Un projet que les <strong>socialistes schaerbeekois<\/strong> avaient d\u00e9j\u00e0 imagin\u00e9 comme un potentiel important pour<strong> Schaerbeek<\/strong> dans leur programme des<strong> \u00e9lections communales<\/strong> de 2012. Maintenant, les choses se pr\u00e9cisent.<\/p>\n<p>La <strong>VRT et la RTBF<\/strong> resteront bien \u00e0 <strong>Reyers<\/strong> mais construiront de nouveaux b\u00e2timents. La <strong>VRT<\/strong> a d\u00e9j\u00e0 choisi son projet architectural tandis que celui de \u00a0la<strong> RTBF\u00a0<\/strong>est en cours.<\/p>\n<p>L&rsquo;id\u00e9e est ausis d&rsquo;implanter des antennes de <strong>hautes \u00e9coles sp\u00e9cialis\u00e9es en communication et m\u00e9dias<\/strong> et surtout d&rsquo;ouvrir ce vaste espace aujourd&rsquo;hui clos au public. Ainsi, un parc de 8 hectares sera accessible au public. Un projet qui changera incontestablement le visage du <strong>quartier Reyers.\u00a0\u00a0<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&rsquo;un des grands projets de la R\u00e9gion de Bruxelles-Capitale est la Cit\u00e9 des M\u00e9dias \u00e0 Reyers. Un projet que les socialistes schaerbeekois avaient d\u00e9j\u00e0 imagin\u00e9 comme un potentiel important pour Schaerbeek dans leur programme des \u00e9lections communales de 2012. Maintenant, les choses se pr\u00e9cisent. La VRT et la RTBF resteront bien \u00e0 Reyers mais construiront [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-20591","post","type-post","status-publish","format-standard","hentry","category-actualites-schaerbeekoises","has-post-title","has-post-date","has-post-category","has-post-tag","has-post-comment","has-post-author",""],"builder_content":"","_links":{"self":[{"href":"https:\/\/www.jeanpierrevangorp.info\/site\/wp-json\/wp\/v2\/posts\/20591"}],"collection":[{"href":"https:\/\/www.jeanpierrevangorp.info\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jeanpierrevangorp.info\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jeanpierrevangorp.info\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jeanpierrevangorp.info\/site\/wp-json\/wp\/v2\/comments?post=20591"}],"version-history":[{"count":1,"href":"https:\/\/www.jeanpierrevangorp.info\/site\/wp-json\/wp\/v2\/posts\/20591\/revisions"}],"predecessor-version":[{"id":20593,"href":"https:\/\/www.jeanpierrevangorp.info\/site\/wp-json\/wp\/v2\/posts\/20591\/revisions\/20593"}],"wp:attachment":[{"href":"https:\/\/www.jeanpierrevangorp.info\/site\/wp-json\/wp\/v2\/media?parent=20591"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jeanpierrevangorp.info\/site\/wp-json\/wp\/v2\/categories?post=20591"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jeanpierrevangorp.info\/site\/wp-json\/wp\/v2\/tags?post=20591"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}