{"id":20710,"date":"2015-06-16T07:16:53","date_gmt":"2015-06-16T06:16:53","guid":{"rendered":"http:\/\/www.jeanpierrevangorp.info\/site\/?p=20710"},"modified":"2015-06-16T07:16:53","modified_gmt":"2015-06-16T06:16:53","slug":"fete-de-la-musique-2015-a-schaerbeek","status":"publish","type":"post","link":"https:\/\/www.jeanpierrevangorp.info\/site\/fete-de-la-musique-2015-a-schaerbeek\/","title":{"rendered":"F\u00eate de la musique 2015 \u00e0 Schaerbeek"},"content":{"rendered":"<p style=\"text-align: center;\"><a href=\"https:\/\/www.jeanpierrevangorp.info\/site\/wp-content\/uploads\/2015\/06\/image-2353.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-20711\" alt=\"image-2353\" src=\"https:\/\/www.jeanpierrevangorp.info\/site\/wp-content\/uploads\/2015\/06\/image-2353-309x464.jpg\" width=\"309\" height=\"464\" srcset=\"https:\/\/www.jeanpierrevangorp.info\/site\/wp-content\/uploads\/2015\/06\/image-2353-309x464.jpg 309w, https:\/\/www.jeanpierrevangorp.info\/site\/wp-content\/uploads\/2015\/06\/image-2353.jpg 340w\" sizes=\"(max-width: 309px) 100vw, 309px\" \/><\/a><\/p>\n<p>Cette ann\u00e9e, <strong>Schaerbeek<\/strong> organise la <strong>F\u00eate de la musique avenue Huart Hamoir<\/strong> en face de la<strong> Gare de Schaerbeek<\/strong> et non plus Place Jamblinne de Meeux. <strong>Samedi 20 ju<\/strong>in \u00e0 partir de 14 heures, les concerts commenceront. En voici le d\u00e9tail :<\/p>\n<ul>\n<li>14:00 : Genevi\u00e8ve Laloy<\/li>\n<li>15:00 : La Clinik du docteur Poembak<\/li>\n<li>16:00 : Chibida Dumbu<\/li>\n<li>17:00 : La Clinik du docteur Poembak<\/li>\n<li>18:00 : Louvat Bros<\/li>\n<li>19:00 : Les Taupes qui boivent du Lait<\/li>\n<li>20:00 : On prend l&rsquo;air (OPLA)<\/li>\n<li>21:00 : Les Taupes qui boivent du Lait<\/li>\n<li>22:00 : OPMOC<\/li>\n<\/ul>\n<p>A noter que les <strong>musiciens schaerbeekois<\/strong> (le groupe doit au moins compter un membre domicili\u00e9 \u00e0 Schaerbeek) pourront y vendre leurs CD&rsquo;s et faire la promotion de leurs prochains concerts. Il leur suffit de se faire conna\u00eetre aupr\u00e8s du service culture (nberghmans@schaerbeek.irisnet.be) et d&rsquo;apporter leurs CD&rsquo;s et leurs tracts le jour de la f\u00eate.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cette ann\u00e9e, Schaerbeek organise la F\u00eate de la musique avenue Huart Hamoir en face de la Gare de Schaerbeek et non plus Place Jamblinne de Meeux. Samedi 20 juin \u00e0 partir de 14 heures, les concerts commenceront. En voici le d\u00e9tail : 14:00 : Genevi\u00e8ve Laloy 15:00 : La Clinik du docteur Poembak 16:00 : [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-20710","post","type-post","status-publish","format-standard","hentry","category-actualites-schaerbeekoises","has-post-title","has-post-date","has-post-category","has-post-tag","has-post-comment","has-post-author",""],"builder_content":"","_links":{"self":[{"href":"https:\/\/www.jeanpierrevangorp.info\/site\/wp-json\/wp\/v2\/posts\/20710"}],"collection":[{"href":"https:\/\/www.jeanpierrevangorp.info\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jeanpierrevangorp.info\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jeanpierrevangorp.info\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jeanpierrevangorp.info\/site\/wp-json\/wp\/v2\/comments?post=20710"}],"version-history":[{"count":1,"href":"https:\/\/www.jeanpierrevangorp.info\/site\/wp-json\/wp\/v2\/posts\/20710\/revisions"}],"predecessor-version":[{"id":20712,"href":"https:\/\/www.jeanpierrevangorp.info\/site\/wp-json\/wp\/v2\/posts\/20710\/revisions\/20712"}],"wp:attachment":[{"href":"https:\/\/www.jeanpierrevangorp.info\/site\/wp-json\/wp\/v2\/media?parent=20710"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jeanpierrevangorp.info\/site\/wp-json\/wp\/v2\/categories?post=20710"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jeanpierrevangorp.info\/site\/wp-json\/wp\/v2\/tags?post=20710"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}