{"id":9997,"date":"2011-05-04T05:32:38","date_gmt":"2011-05-04T04:32:38","guid":{"rendered":"http:\/\/www.jeanpierrevangorp.info\/site\/?p=9997"},"modified":"2011-05-04T05:33:54","modified_gmt":"2011-05-04T04:33:54","slug":"la-rage-taxatoire-schaerbeekoise","status":"publish","type":"post","link":"https:\/\/www.jeanpierrevangorp.info\/site\/la-rage-taxatoire-schaerbeekoise\/","title":{"rendered":"La rage taxatoire schaerbeekoise"},"content":{"rendered":"<p>Nouvel \u00e9pisode dans la <strong>politique taxatoire schaerbeekoise<\/strong> : en plus du pr\u00e9compte immobilier si vous \u00eates propri\u00e9taire d&rsquo;un immeuble et r\u00e9sidez hors des fronti\u00e8res communales, vous serez \u00e0 nouveau tax\u00e9s ! Le point sera largement d\u00e9battu ce soir au Conseil communal quant \u00e0 sa l\u00e9galit\u00e9 mais aussi quant \u00e0 ses r\u00e9percussions notamment sur les <strong>logements de propri\u00e9taires non Schaerbeekois<\/strong> qui auraient donn\u00e9 leur patrimoine en gestion par exemple \u00e0 une <strong>agence sociale immobili\u00e8re<\/strong>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nouvel \u00e9pisode dans la politique taxatoire schaerbeekoise : en plus du pr\u00e9compte immobilier si vous \u00eates propri\u00e9taire d&rsquo;un immeuble et r\u00e9sidez hors des fronti\u00e8res communales, vous serez \u00e0 nouveau tax\u00e9s ! Le point sera largement d\u00e9battu ce soir au Conseil communal quant \u00e0 sa l\u00e9galit\u00e9 mais aussi quant \u00e0 ses r\u00e9percussions notamment sur les logements [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-9997","post","type-post","status-publish","format-standard","hentry","category-conseilcommunal","has-post-title","has-post-date","has-post-category","has-post-tag","has-post-comment","has-post-author",""],"builder_content":"","_links":{"self":[{"href":"https:\/\/www.jeanpierrevangorp.info\/site\/wp-json\/wp\/v2\/posts\/9997"}],"collection":[{"href":"https:\/\/www.jeanpierrevangorp.info\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jeanpierrevangorp.info\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jeanpierrevangorp.info\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jeanpierrevangorp.info\/site\/wp-json\/wp\/v2\/comments?post=9997"}],"version-history":[{"count":0,"href":"https:\/\/www.jeanpierrevangorp.info\/site\/wp-json\/wp\/v2\/posts\/9997\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.jeanpierrevangorp.info\/site\/wp-json\/wp\/v2\/media?parent=9997"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jeanpierrevangorp.info\/site\/wp-json\/wp\/v2\/categories?post=9997"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jeanpierrevangorp.info\/site\/wp-json\/wp\/v2\/tags?post=9997"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}